{"id":84196,"date":"2024-10-22T10:26:31","date_gmt":"2024-10-22T08:26:31","guid":{"rendered":"https:\/\/marottaevolution.it\/marotta-evolution-en-el-sic-de-caserta-la-presentacion-de-una-asociacion-y-de-una-maquina-unica-en-su-genero\/"},"modified":"2026-06-18T10:40:48","modified_gmt":"2026-06-18T08:40:48","slug":"marotta-evolution-en-el-sic-de-caserta-la-presentacion-de-una-asociacion-y-de-una-maquina-unica-en-su-genero","status":"publish","type":"post","link":"https:\/\/marottaevolution.it\/es\/marotta-evolution-en-el-sic-de-caserta-la-presentacion-de-una-asociacion-y-de-una-maquina-unica-en-su-genero\/","title":{"rendered":"Marotta Evolution en el SIC de Caserta, la presentaci\u00f3n de una asociaci\u00f3n y de una m\u00e1quina \u00fanica en su g\u00e9nero."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"84196\" class=\"elementor elementor-84196 elementor-82432\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a4c997f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a4c997f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c054ab\" data-id=\"2c054ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10def9bd elementor-widget elementor-widget-text-editor\" data-id=\"10def9bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<p>Del 18 al 20 de octubre de 2024 Marotta Evolution particip\u00f3 como expositor en el Sal\u00f3n de la Industria Casearia y Conserviera SIC de Caserta.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><\/figure>\n\n<p>La participaci\u00f3n de Marotta Evolution en el evento ferial no solo fue un gran \u00e9xito; de hecho, la empresa destac\u00f3 por su innovaci\u00f3n y su vanguardia tecnol\u00f3gica, sino que tambi\u00e9n despert\u00f3 un gran inter\u00e9s la asociaci\u00f3n con las tres empresas del sector de la automatizaci\u00f3n industrial, Karr Italiana, AMC y Almac, las cuales, juntas, dieron vida a MAXIMA, un grupo, una uni\u00f3n, bautizada precisamente durante el primer d\u00eda del SIC.<\/p>\n\n<div class=\"wp-block-group\">\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-82445 size-large\" style=\"object-fit: contain; width: 1001px; height: 667px;\" src=\"https:\/\/marottaevolution.it\/wp-content\/uploads\/2024\/10\/MAXIMA-marotta-SIC-1024x843.jpg\" alt=\"\" width=\"1024\" height=\"843\"><\/figure>\n<\/div>\n\n<p>El viernes 18 de octubre de 2024, tuvo lugar el premio MAXIMA, galard\u00f3n a la innovaci\u00f3n industrial y a la excelencia en el sector de la automatizaci\u00f3n. El stand de Marotta Evolution fue la sede de este evento, que cont\u00f3 con la presencia del presidente del SIC, Massimo Coda, de Michele Erra, organizador de la feria, de Adolfo Bottazzo, vicepresidente de Confindustria de Caserta, as\u00ed como del consejero regional de la Regi\u00f3n de Campania, Andrea Volpe. Tambi\u00e9n estuvo presente el representante de Cibus Tec de Fiere di Parma, Alberto Savina, quien afirm\u00f3 la importancia de la innovaci\u00f3n aportada por MAXIMA al mundo de la industria l\u00e1ctea.<br\/>Fueron premiados los cuatro empresarios cuyo talento dio vida a MAXIMA, es decir, Carmine Marotta por Marotta Evolution, Fabio Marano por AMC, Ettore Oldrini por Karr Italiana y Paride Lotti por Almac, adem\u00e1s de un premio tambi\u00e9n para Massimo Coda, presidente del SIC.   <\/p>\n<p>En el gran espacio expositivo de Marotta Evolution en el SIC de Caserta, se puso en funcionamiento la nueva y sorprendente m\u00e1quina MAXIMA, capaz de realizar todo el proceso de creaci\u00f3n de la burrata, desde la leche hasta el envasado.<\/p>\n<p>Durante los tres d\u00edas del evento, Marotta Evolution brill\u00f3 como solo las grandes empresas innovadoras saben hacerlo, gracias a encuentros, alianzas con clientes antiguos y nuevos, as\u00ed como degustaciones y demostraciones de producci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Del 18 al 20 de octubre de 2024 Marotta Evolution estar\u00e1 presente en el Sal\u00f3n Industria Casearia y Conserviera SIC de Caserta.<\/p>\n","protected":false},"author":1,"featured_media":84195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[128,124,126,127],"tags":[130,125,131,129,132,133],"class_list":["post-84196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiere","category-comunicaciones","category-novedades","category-revista-de-prensa","tag-caserta","tag-feria","tag-marotta","tag-marotta-evolution","tag-maxima","tag-sic"],"acf":[],"_links":{"self":[{"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/posts\/84196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/comments?post=84196"}],"version-history":[{"count":0,"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/posts\/84196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/media\/84195"}],"wp:attachment":[{"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/media?parent=84196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/categories?post=84196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marottaevolution.it\/es\/wp-json\/wp\/v2\/tags?post=84196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}